{"id":128,"count":1,"description":"","link":"https:\/\/frankdoorhof.com\/music\/tag\/re-amp-2\/","name":"re-amp","slug":"re-amp-2","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>re-amp Archives - Frank Doorhof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frankdoorhof.com\/music\/tag\/re-amp-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"re-amp Archives - Frank Doorhof\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frankdoorhof.com\/music\/tag\/re-amp-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Frank Doorhof\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/frankdoorhof.com\\\/music\\\/tag\\\/re-amp-2\\\/\",\"url\":\"https:\\\/\\\/frankdoorhof.com\\\/music\\\/tag\\\/re-amp-2\\\/\",\"name\":\"re-amp Archives - Frank Doorhof\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frankdoorhof.com\\\/music\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frankdoorhof.com\\\/music\\\/tag\\\/re-amp-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frankdoorhof.com\\\/music\\\/tag\\\/re-amp-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/frankdoorhof.com\\\/music\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"re-amp\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frankdoorhof.com\\\/music\\\/#website\",\"url\":\"https:\\\/\\\/frankdoorhof.com\\\/music\\\/\",\"name\":\"Frank Doorhof\",\"description\":\"The musical world of Frank Doorhof. Stream my music via your favorite streaming service\",\"publisher\":{\"@id\":\"https:\\\/\\\/frankdoorhof.com\\\/music\\\/#\\\/schema\\\/person\\\/a82ca9090d1c9eb08baf8bd77766e944\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frankdoorhof.com\\\/music\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/frankdoorhof.com\\\/music\\\/#\\\/schema\\\/person\\\/a82ca9090d1c9eb08baf8bd77766e944\",\"name\":\"Frank Doorhof\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cad3c88f846ab73cf237d1dcccd105eef1c18416ef1aff3194c88f7aab1a88d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cad3c88f846ab73cf237d1dcccd105eef1c18416ef1aff3194c88f7aab1a88d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cad3c88f846ab73cf237d1dcccd105eef1c18416ef1aff3194c88f7aab1a88d?s=96&d=mm&r=g\",\"caption\":\"Frank Doorhof\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cad3c88f846ab73cf237d1dcccd105eef1c18416ef1aff3194c88f7aab1a88d?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/frankdoorhof.com\\\/music\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"re-amp Archives - Frank Doorhof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frankdoorhof.com\/music\/tag\/re-amp-2\/","og_locale":"en_US","og_type":"article","og_title":"re-amp Archives - Frank Doorhof","og_url":"https:\/\/frankdoorhof.com\/music\/tag\/re-amp-2\/","og_site_name":"Frank Doorhof","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/frankdoorhof.com\/music\/tag\/re-amp-2\/","url":"https:\/\/frankdoorhof.com\/music\/tag\/re-amp-2\/","name":"re-amp Archives - Frank Doorhof","isPartOf":{"@id":"https:\/\/frankdoorhof.com\/music\/#website"},"breadcrumb":{"@id":"https:\/\/frankdoorhof.com\/music\/tag\/re-amp-2\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/frankdoorhof.com\/music\/tag\/re-amp-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/frankdoorhof.com\/music\/"},{"@type":"ListItem","position":2,"name":"re-amp"}]},{"@type":"WebSite","@id":"https:\/\/frankdoorhof.com\/music\/#website","url":"https:\/\/frankdoorhof.com\/music\/","name":"Frank Doorhof","description":"The musical world of Frank Doorhof. Stream my music via your favorite streaming service","publisher":{"@id":"https:\/\/frankdoorhof.com\/music\/#\/schema\/person\/a82ca9090d1c9eb08baf8bd77766e944"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frankdoorhof.com\/music\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/frankdoorhof.com\/music\/#\/schema\/person\/a82ca9090d1c9eb08baf8bd77766e944","name":"Frank Doorhof","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4cad3c88f846ab73cf237d1dcccd105eef1c18416ef1aff3194c88f7aab1a88d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4cad3c88f846ab73cf237d1dcccd105eef1c18416ef1aff3194c88f7aab1a88d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4cad3c88f846ab73cf237d1dcccd105eef1c18416ef1aff3194c88f7aab1a88d?s=96&d=mm&r=g","caption":"Frank Doorhof"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/4cad3c88f846ab73cf237d1dcccd105eef1c18416ef1aff3194c88f7aab1a88d?s=96&d=mm&r=g"},"sameAs":["https:\/\/frankdoorhof.com\/music"]}]}},"_links":{"self":[{"href":"https:\/\/frankdoorhof.com\/music\/wp-json\/wp\/v2\/tags\/128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frankdoorhof.com\/music\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/frankdoorhof.com\/music\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/frankdoorhof.com\/music\/wp-json\/wp\/v2\/posts?tags=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}